{"id":251949,"date":"2026-03-15T00:54:31","date_gmt":"2026-03-14T23:54:31","guid":{"rendered":"https:\/\/schweizversand.ch\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/"},"modified":"2026-09-01T16:02:35","modified_gmt":"2026-09-01T14:02:35","slug":"hudora-1-bremsblech-zu-scooter-clvr-wb-eol","status":"publish","type":"product","link":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/","title":{"rendered":"Hudora 1 brake plate for Scooter CLVR (WB) (EOL)"},"content":{"rendered":"<p>Brake plate including mounting hardware for the CLVR 215 &amp; 250 scooters (14830, 14831, 14834, 14835)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hudora brake plate with mounting hardware for Scooter CLVR 215 &amp; 250 models, ensuring reliable stopping power and easy installation.<\/p>\n","protected":false},"featured_media":159026,"template":"","meta":[],"product_brand":[],"product_cat":[38505],"product_tag":[],"class_list":["post-251949","product","type-product","status-publish","has-post-thumbnail","product_cat-scooter","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)<\/title>\n<meta name=\"description\" content=\"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 &amp; 250 (14830, 14831, 14834, 14835)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)\" \/>\n<meta property=\"og:description\" content=\"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 &amp; 250 (14830, 14831, 14834, 14835)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schweizversand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:02:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471523744.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/\",\"name\":\"Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471523744.jpg\",\"datePublished\":\"2026-03-14T23:54:31+00:00\",\"dateModified\":\"2026-09-01T14:02:35+00:00\",\"description\":\"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 & 250 (14830, 14831, 14834, 14835)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471523744.jpg\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471523744.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt\\\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spare parts\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt-kategorie\\\/spare-parts\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hudora\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt-kategorie\\\/spare-parts\\\/hudora\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Scooter\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/produkt-kategorie\\\/spare-parts\\\/hudora\\\/scooter\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Hudora 1 brake plate for Scooter CLVR (WB) (EOL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/\",\"name\":\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\",\"description\":\"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h\",\"publisher\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#organization\"},\"alternateName\":\"Schweizversand.ch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#organization\",\"name\":\"Schweizversand.ch\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"width\":404,\"height\":404,\"caption\":\"Schweizversand.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schweizversand\",\"https:\\\/\\\/www.instagram.com\\\/schweizversand.ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)","description":"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 & 250 (14830, 14831, 14834, 14835)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/","og_locale":"en_US","og_type":"article","og_title":"Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)","og_description":"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 & 250 (14830, 14831, 14834, 14835)","og_url":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/","og_site_name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","article_publisher":"https:\/\/www.facebook.com\/Schweizversand","article_modified_time":"2026-09-01T14:02:35+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471523744.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/","url":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/","name":"Hudora 1 Bremsblech zu Scooter CLVR (WB) (EOL)","isPartOf":{"@id":"https:\/\/schweizversand.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/#primaryimage"},"image":{"@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/#primaryimage"},"thumbnailUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471523744.jpg","datePublished":"2026-03-14T23:54:31+00:00","dateModified":"2026-09-01T14:02:35+00:00","description":"Bremsblech inkl. Befestigungsmaterial f\u00fcr die Scooter CLVR 215 & 250 (14830, 14831, 14834, 14835)","breadcrumb":{"@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/#primaryimage","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471523744.jpg","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471523744.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/schweizversand.ch\/en\/produkt\/hudora-1-bremsblech-zu-scooter-clvr-wb-eol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schweizversand.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/schweizversand.ch\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Spare parts","item":"https:\/\/schweizversand.ch\/en\/produkt-kategorie\/spare-parts\/"},{"@type":"ListItem","position":4,"name":"Hudora","item":"https:\/\/schweizversand.ch\/en\/produkt-kategorie\/spare-parts\/hudora\/"},{"@type":"ListItem","position":5,"name":"Scooter","item":"https:\/\/schweizversand.ch\/en\/produkt-kategorie\/spare-parts\/hudora\/scooter\/"},{"@type":"ListItem","position":6,"name":"Hudora 1 brake plate for Scooter CLVR (WB) (EOL)"}]},{"@type":"WebSite","@id":"https:\/\/schweizversand.ch\/en\/#website","url":"https:\/\/schweizversand.ch\/en\/","name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","description":"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h","publisher":{"@id":"https:\/\/schweizversand.ch\/en\/#organization"},"alternateName":"Schweizversand.ch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schweizversand.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schweizversand.ch\/en\/#organization","name":"Schweizversand.ch","url":"https:\/\/schweizversand.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schweizversand.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","width":404,"height":404,"caption":"Schweizversand.ch"},"image":{"@id":"https:\/\/schweizversand.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schweizversand","https:\/\/www.instagram.com\/schweizversand.ch\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/product\/251949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/media\/159026"}],"wp:attachment":[{"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/media?parent=251949"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/product_brand?post=251949"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/product_cat?post=251949"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schweizversand.ch\/en\/wp-json\/wp\/v2\/product_tag?post=251949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}