{"id":253451,"date":"2026-03-14T23:20:43","date_gmt":"2026-03-14T22:20:43","guid":{"rendered":"https:\/\/schweizversand.ch\/produkt\/plantoys-holzspielzeug-schiebehase\/"},"modified":"2026-09-01T16:05:44","modified_gmt":"2026-09-01T14:05:44","slug":"plantoys-holzspielzeug-schiebehase","status":"publish","type":"product","link":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/","title":{"rendered":"Lapin \u00e0 pousser en bois Plantoys"},"content":{"rendered":"<p>PlanToys Lapin \u00e0 pousser \u2013 Un lapin rose sauteur pour les petits explorateurs !<\/p>\n<p>Joyeux, color\u00e9 et pr\u00eat \u00e0 bondir !<\/p>\n<p>Avec le lapin \u00e0 pousser PlanToys, con\u00e7u avec amour, les enfants d\u00e8s 12 mois s&rsquo;amuseront activement. Sa poign\u00e9e souple est parfaitement adapt\u00e9e aux petites mains et sa forme articul\u00e9e rend chaque mouvement amusant. Pousser le lapin stimule l&rsquo;imagination, d\u00e9veloppe la motricit\u00e9 fine et favorise la compr\u00e9hension de la relation de cause \u00e0 effet.<\/p>\n<p>Jouet en bois de haute qualit\u00e9 \u2013 durable et s\u00fbr<\/p>\n<p>Poign\u00e9e ergonomique adapt\u00e9e aux petites mains<\/p>\n<p>Favorise le mouvement, la coordination et la cr\u00e9ativit\u00e9<\/p>\n<p>Recommand\u00e9 \u00e0 partir de 12 mois<\/p>\n<p>Sautez avec le plus mignon des lapins \u00e0 roulettes !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plantoys Lapin \u00e0 pousser en bois, id\u00e9al pour les enfants d\u00e8s 12 mois, stimule la motricit\u00e9 fine, la coordination et l\u2019imagination avec un design color\u00e9 et ergonomique.<\/p>\n","protected":false},"featured_media":156680,"template":"","meta":[],"product_brand":[],"product_cat":[38111],"product_tag":[],"class_list":["post-253451","product","type-product","status-publish","has-post-thumbnail","product_cat-jouets-pour-bebes","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch<\/title>\n<meta name=\"description\" content=\"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch\" \/>\n<meta property=\"og:description\" content=\"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schweizversand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:05:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471859085.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/\",\"name\":\"Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471859085.jpg\",\"datePublished\":\"2026-03-14T22:20:43+00:00\",\"dateModified\":\"2026-09-01T14:05:44+00:00\",\"description\":\"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471859085.jpg\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/5471859085.jpg\",\"width\":1024,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/plantoys-holzspielzeug-schiebehase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B\u00e9b\u00e9 et parents\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt-kategorie\\\/bebe-et-parents\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Jouets pour b\u00e9b\u00e9s\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt-kategorie\\\/bebe-et-parents\\\/jouets-pour-bebes\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Lapin \u00e0 pousser en bois Plantoys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/\",\"name\":\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\",\"description\":\"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h\",\"publisher\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#organization\"},\"alternateName\":\"Schweizversand.ch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#organization\",\"name\":\"Schweizversand.ch\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"width\":404,\"height\":404,\"caption\":\"Schweizversand.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schweizversand\",\"https:\\\/\\\/www.instagram.com\\\/schweizversand.ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch","description":"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/","og_locale":"fr_FR","og_type":"article","og_title":"Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch","og_description":"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.","og_url":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/","og_site_name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","article_publisher":"https:\/\/www.facebook.com\/Schweizversand","article_modified_time":"2026-09-01T14:05:44+00:00","og_image":[{"width":1024,"height":886,"url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471859085.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/","url":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/","name":"Plantoys Holzspielzeug Schiebehase | Jetzt kaufen | Schweizversand.ch","isPartOf":{"@id":"https:\/\/schweizversand.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/#primaryimage"},"image":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/#primaryimage"},"thumbnailUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471859085.jpg","datePublished":"2026-03-14T22:20:43+00:00","dateModified":"2026-09-01T14:05:44+00:00","description":"Plantoys Holzspielzeug Schiebehase g\u00fcnstig kaufen bei Schweizversand.ch. Schnelle Lieferung in der Schweiz. Gratisversand ab CHF 50.","breadcrumb":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/#primaryimage","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471859085.jpg","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/02\/5471859085.jpg","width":1024,"height":886},{"@type":"BreadcrumbList","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/plantoys-holzspielzeug-schiebehase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schweizversand.ch\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/schweizversand.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"B\u00e9b\u00e9 et parents","item":"https:\/\/schweizversand.ch\/fr\/produkt-kategorie\/bebe-et-parents\/"},{"@type":"ListItem","position":4,"name":"Jouets pour b\u00e9b\u00e9s","item":"https:\/\/schweizversand.ch\/fr\/produkt-kategorie\/bebe-et-parents\/jouets-pour-bebes\/"},{"@type":"ListItem","position":5,"name":"Lapin \u00e0 pousser en bois Plantoys"}]},{"@type":"WebSite","@id":"https:\/\/schweizversand.ch\/fr\/#website","url":"https:\/\/schweizversand.ch\/fr\/","name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","description":"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h","publisher":{"@id":"https:\/\/schweizversand.ch\/fr\/#organization"},"alternateName":"Schweizversand.ch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schweizversand.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schweizversand.ch\/fr\/#organization","name":"Schweizversand.ch","url":"https:\/\/schweizversand.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schweizversand.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","width":404,"height":404,"caption":"Schweizversand.ch"},"image":{"@id":"https:\/\/schweizversand.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schweizversand","https:\/\/www.instagram.com\/schweizversand.ch\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product\/253451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/media\/156680"}],"wp:attachment":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/media?parent=253451"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=253451"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=253451"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=253451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}