{"id":279899,"date":"2026-08-11T18:45:26","date_gmt":"2026-08-11T16:45:26","guid":{"rendered":"https:\/\/schweizversand.ch\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/"},"modified":"2026-09-01T16:04:05","modified_gmt":"2026-09-01T14:04:05","slug":"champ-herren-thermo-freizeit-socken-6-er-pack-2","status":"publish","type":"product","link":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/","title":{"rendered":"CHAMP Chaussettes thermiques \/ de loisirs pour hommes, lot de 6"},"content":{"rendered":"<h1><strong>Chaussettes de loisirs pour hommes, lot de 6<\/strong><\/h1>\n<div>D\u00e9couvrez le confort ultime et la polyvalence de nos <strong>chaussettes de loisirs pour hommes, lot de 6<\/strong>. Ces chaussettes sont le choix parfait pour le quotidien et offrent une combinaison id\u00e9ale de <strong>durabilit\u00e9 et de confort agr\u00e9able \u00e0 porter<\/strong>.<\/p>\n<\/div>\n<div><strong>Confort et mat\u00e9riau<\/strong><br \/>Ces chaussettes de haute qualit\u00e9 en <strong>polyester et coton<\/strong> sont compos\u00e9es d\u2019un m\u00e9lange de mat\u00e9riaux soigneusement \u00e9tudi\u00e9 : 65 % polyester, 20 % coton, 13 % polypropyl\u00e8ne et 2 % \u00e9lasthanne. Cette composition assure une <strong>respirabilit\u00e9<\/strong>, une tenue de forme et un ajustement optimal. Profitez d\u2019un confort agr\u00e9able toute la journ\u00e9e, que ce soit au travail ou pendant vos loisirs.<\/p>\n<\/div>\n<div><strong>Polyvalence et ajustement<\/strong><br \/>Le pratique <strong>lot de chaussettes pour hommes<\/strong> vous offre six paires pour toutes les occasions. Les <strong>chaussettes pour hommes taille 39-42<\/strong> sont sp\u00e9cialement con\u00e7ues pour ces tailles et garantissent un maintien s\u00fbr sans glisser. Id\u00e9ales comme <strong>chaussettes de loisirs pour hommes<\/strong> pour le sport, la d\u00e9tente ou un usage quotidien.<\/p>\n<\/div>\n<div><strong>D\u00e9tails du produit<\/strong><br \/>&#8211; Taille : 39-42<br \/>&#8211; Mat\u00e9riau : 65 % polyester, 20 % coton, 13 % polypropyl\u00e8ne, 2 % \u00e9lasthanne<br \/>&#8211; Contenu de l\u2019emballage : 6 paires de chaussettes<\/p>\n<\/div>\n<div>Investissez dans ce lot de 6 et d\u00e9couvrez la diff\u00e9rence de qualit\u00e9 et de confort que nos <strong>chaussettes de loisirs pour hommes<\/strong> CHAMP offrent.<\/p>\n<p>Gris chin\u00e9 \/ Noir chin\u00e9 \/ Bleu chin\u00e9&nbsp;<\/p><\/div>\n<div><\/div>\n<div>La couleur ne peut pas \u00eatre choisie.&nbsp;<br \/>Prix par lot de 6<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHAMP chaussettes thermiques et de loisirs pour hommes, lot de 6 paires, confort optimal, respirantes et r\u00e9sistantes, taille 39-42, parfaites pour un usage quotidien.<\/p>\n","protected":false},"featured_media":277072,"template":"","meta":[],"product_brand":[],"product_cat":[38329],"product_tag":[],"class_list":["post-279899","product","type-product","status-publish","has-post-thumbnail","product_cat-herrenwaesche","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHAMP Herren Thermo \/ Freizeit Socken 6-er Pack<\/title>\n<meta name=\"description\" content=\"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHAMP Herren Thermo \/ Freizeit Socken 6-er Pack\" \/>\n<meta property=\"og:description\" content=\"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schweizversand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:04:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6052482863.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/\",\"name\":\"CHAMP Herren Thermo \\\/ Freizeit Socken 6-er Pack\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6052482863.jpg\",\"datePublished\":\"2026-08-11T16:45:26+00:00\",\"dateModified\":\"2026-09-01T14:04:05+00:00\",\"description\":\"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6052482863.jpg\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6052482863.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt\\\/champ-herren-thermo-freizeit-socken-6-er-pack-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mode\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt-kategorie\\\/mode-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mode masculine\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt-kategorie\\\/mode-fr\\\/mode-masculine\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Sous-v\u00eatements pour hommes\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/produkt-kategorie\\\/mode-fr\\\/mode-masculine\\\/herrenwaesche\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"CHAMP Chaussettes thermiques \\\/ de loisirs pour hommes, lot de 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/\",\"name\":\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\",\"description\":\"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h\",\"publisher\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#organization\"},\"alternateName\":\"Schweizversand.ch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#organization\",\"name\":\"Schweizversand.ch\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"width\":404,\"height\":404,\"caption\":\"Schweizversand.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schweizversand\",\"https:\\\/\\\/www.instagram.com\\\/schweizversand.ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHAMP Herren Thermo \/ Freizeit Socken 6-er Pack","description":"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/","og_locale":"fr_FR","og_type":"article","og_title":"CHAMP Herren Thermo \/ Freizeit Socken 6-er Pack","og_description":"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe","og_url":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/","og_site_name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","article_publisher":"https:\/\/www.facebook.com\/Schweizversand","article_modified_time":"2026-09-01T14:04:05+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6052482863.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/","url":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/","name":"CHAMP Herren Thermo \/ Freizeit Socken 6-er Pack","isPartOf":{"@id":"https:\/\/schweizversand.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/#primaryimage"},"image":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/#primaryimage"},"thumbnailUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6052482863.jpg","datePublished":"2026-08-11T16:45:26+00:00","dateModified":"2026-09-01T14:04:05+00:00","description":"Herren Freizeitsocken 6er Pack Entdecken Sie den ultimativen Komfort und die Vielseitigkeit unserer Herren Freizeitsocken 6er Pack . Diese Socken sind die perfe","breadcrumb":{"@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/#primaryimage","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6052482863.jpg","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6052482863.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/schweizversand.ch\/fr\/produkt\/champ-herren-thermo-freizeit-socken-6-er-pack-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schweizversand.ch\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/schweizversand.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Mode","item":"https:\/\/schweizversand.ch\/fr\/produkt-kategorie\/mode-fr\/"},{"@type":"ListItem","position":4,"name":"Mode masculine","item":"https:\/\/schweizversand.ch\/fr\/produkt-kategorie\/mode-fr\/mode-masculine\/"},{"@type":"ListItem","position":5,"name":"Sous-v\u00eatements pour hommes","item":"https:\/\/schweizversand.ch\/fr\/produkt-kategorie\/mode-fr\/mode-masculine\/herrenwaesche\/"},{"@type":"ListItem","position":6,"name":"CHAMP Chaussettes thermiques \/ de loisirs pour hommes, lot de 6"}]},{"@type":"WebSite","@id":"https:\/\/schweizversand.ch\/fr\/#website","url":"https:\/\/schweizversand.ch\/fr\/","name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","description":"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h","publisher":{"@id":"https:\/\/schweizversand.ch\/fr\/#organization"},"alternateName":"Schweizversand.ch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schweizversand.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schweizversand.ch\/fr\/#organization","name":"Schweizversand.ch","url":"https:\/\/schweizversand.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schweizversand.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","width":404,"height":404,"caption":"Schweizversand.ch"},"image":{"@id":"https:\/\/schweizversand.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schweizversand","https:\/\/www.instagram.com\/schweizversand.ch\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product\/279899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/media\/277072"}],"wp:attachment":[{"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/media?parent=279899"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=279899"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=279899"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schweizversand.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=279899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}