{"id":282292,"date":"2026-08-11T18:45:09","date_gmt":"2026-08-11T16:45:09","guid":{"rendered":"https:\/\/schweizversand.ch\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/"},"modified":"2026-09-01T16:06:02","modified_gmt":"2026-09-01T14:06:02","slug":"xq-max-steel-tip-dartpfeile-set-23g","status":"publish","type":"product","link":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/","title":{"rendered":"XQ Max Set di Freccette Steel Tip 23g"},"content":{"rendered":"<h1><strong>XQ Max Steel Tip Dartpfeile Set 23 g (argento, 3 pz.)<\/strong><\/h1>\n<div>Questo set di <strong>freccette<\/strong> di alta qualit\u00e0 convince con una elegante finitura argento ed \u00e8 ideale per i giocatori che apprezzano precisione e controllo. Le <strong>Steeldarts 23g<\/strong> offrono, grazie al loro peso bilanciato, una sensazione di lancio stabile e precisa.<\/p>\n<\/div>\n<div><strong>Massima presa e volo preciso<\/strong><br \/>Le <strong>Steel Tip Darts<\/strong> sono dotate di shaft Max-Grip neri e trasparenti (41 mm) con anelli, che garantiscono una presa sicura nella mano. Le <strong>Dart Flights<\/strong> nero-verdi in materiale PET da 100 micron assicurano un volo stabile e uniforme \u2013 tiro dopo tiro.<\/p>\n<\/div>\n<div><strong>Contenuto della confezione<\/strong><br \/>&#8211; 3 <strong>freccette<\/strong> rivestite in argento da 23 g ciascuna<br \/>&#8211; Shaft Max-Grip neri e trasparenti (41 mm) con anelli<br \/>&#8211; Flight PET nero-verdi (100 micron)<br \/>&#8211; Astuccio <strong>Dart<\/strong> nero per un trasporto e una conservazione sicuri<\/p>\n<\/div>\n<div>Ordina oggi stesso questo set completo di <strong>freccette<\/strong> e vivi precisione e stile al bersaglio da freccette.<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Set di freccette XQ Max Steel Tip da 23 g con finitura argento, impugnature Max-Grip e alette in PET per precisione e controllo ottimali ad ogni lancio.<\/p>\n","protected":false},"featured_media":277051,"template":"","meta":[],"product_brand":[],"product_cat":[39192],"product_tag":[],"class_list":["post-282292","product","type-product","status-publish","has-post-thumbnail","product_cat-dart","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XQ Max Steel Tip Dartpfeile Set 23g<\/title>\n<meta name=\"description\" content=\"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XQ Max Steel Tip Dartpfeile Set 23g\" \/>\n<meta property=\"og:description\" content=\"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schweizversand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6031628068.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/\",\"name\":\"XQ Max Steel Tip Dartpfeile Set 23g\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6031628068.jpg\",\"datePublished\":\"2026-08-11T16:45:09+00:00\",\"dateModified\":\"2026-09-01T14:06:02+00:00\",\"description\":\"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6031628068.jpg\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/6031628068.jpg\",\"width\":1024,\"height\":908},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt\\\/xq-max-steel-tip-dartpfeile-set-23g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sport\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt-kategorie\\\/sport-it\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"sport con la palla e freccette\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt-kategorie\\\/sport-it\\\/sport-con-la-palla-e-freccette\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Dart\",\"item\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/produkt-kategorie\\\/sport-it\\\/sport-con-la-palla-e-freccette\\\/dart\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"XQ Max Set di Freccette Steel Tip 23g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/\",\"name\":\"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit\",\"description\":\"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h\",\"publisher\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#organization\"},\"alternateName\":\"Schweizversand.ch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#organization\",\"name\":\"Schweizversand.ch\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"contentUrl\":\"https:\\\/\\\/schweizversand.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Rund_Final-1.png\",\"width\":404,\"height\":404,\"caption\":\"Schweizversand.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/schweizversand.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schweizversand\",\"https:\\\/\\\/www.instagram.com\\\/schweizversand.ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XQ Max Steel Tip Dartpfeile Set 23g","description":"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/","og_locale":"it_IT","og_type":"article","og_title":"XQ Max Steel Tip Dartpfeile Set 23g","og_description":"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler","og_url":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/","og_site_name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","article_publisher":"https:\/\/www.facebook.com\/Schweizversand","article_modified_time":"2026-09-01T14:06:02+00:00","og_image":[{"width":1024,"height":908,"url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6031628068.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/","url":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/","name":"XQ Max Steel Tip Dartpfeile Set 23g","isPartOf":{"@id":"https:\/\/schweizversand.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/#primaryimage"},"image":{"@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/#primaryimage"},"thumbnailUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6031628068.jpg","datePublished":"2026-08-11T16:45:09+00:00","dateModified":"2026-09-01T14:06:02+00:00","description":"XQ Max Steel Tip Dartpfeile Set 23 g (silber, 3 Stk.) Dieses hochwertige Dartpfeile Set \u00fcberzeugt mit einem eleganten silbernen Finish und ist ideal f\u00fcr Spieler","breadcrumb":{"@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/#primaryimage","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6031628068.jpg","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/08\/6031628068.jpg","width":1024,"height":908},{"@type":"BreadcrumbList","@id":"https:\/\/schweizversand.ch\/it\/produkt\/xq-max-steel-tip-dartpfeile-set-23g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schweizversand.ch\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/schweizversand.ch\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Sport","item":"https:\/\/schweizversand.ch\/it\/produkt-kategorie\/sport-it\/"},{"@type":"ListItem","position":4,"name":"sport con la palla e freccette","item":"https:\/\/schweizversand.ch\/it\/produkt-kategorie\/sport-it\/sport-con-la-palla-e-freccette\/"},{"@type":"ListItem","position":5,"name":"Dart","item":"https:\/\/schweizversand.ch\/it\/produkt-kategorie\/sport-it\/sport-con-la-palla-e-freccette\/dart\/"},{"@type":"ListItem","position":6,"name":"XQ Max Set di Freccette Steel Tip 23g"}]},{"@type":"WebSite","@id":"https:\/\/schweizversand.ch\/it\/#website","url":"https:\/\/schweizversand.ch\/it\/","name":"Schweizer Shop f\u00fcr Sport, Spiel und Freizeit","description":"Gratisversand ab 50.- (netto), ab eigenem schweizer Lager, Lieferung innert 48h","publisher":{"@id":"https:\/\/schweizversand.ch\/it\/#organization"},"alternateName":"Schweizversand.ch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schweizversand.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schweizversand.ch\/it\/#organization","name":"Schweizversand.ch","url":"https:\/\/schweizversand.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schweizversand.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","contentUrl":"https:\/\/schweizversand.ch\/wp-content\/uploads\/2026\/03\/Logo_Rund_Final-1.png","width":404,"height":404,"caption":"Schweizversand.ch"},"image":{"@id":"https:\/\/schweizversand.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schweizversand","https:\/\/www.instagram.com\/schweizversand.ch\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/product\/282292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/media\/277051"}],"wp:attachment":[{"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/media?parent=282292"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/product_brand?post=282292"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/product_cat?post=282292"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schweizversand.ch\/it\/wp-json\/wp\/v2\/product_tag?post=282292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}